{"id":10,"date":"2023-12-03T16:10:31","date_gmt":"2023-12-03T15:10:31","guid":{"rendered":"https:\/\/lafourmiailee.wordpress.com\/?page_id=6"},"modified":"2024-04-04T19:02:12","modified_gmt":"2024-04-04T17:02:12","slug":"accueil","status":"publish","type":"page","link":"https:\/\/lafourmiailee.com\/","title":{"rendered":"Accueil"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"10\" class=\"elementor elementor-10\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf1b295 e-con-full e-flex e-con e-parent\" data-id=\"bf1b295\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;background_slideshow_gallery&quot;:[{&quot;id&quot;:123,&quot;url&quot;:&quot;https:\\\/\\\/lafourmiailee.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/dscf2993-1-scaled.jpg&quot;}],&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_blur_effect&quot;:&quot;yes&quot;,&quot;motion_fx_blur_direction&quot;:&quot;in-out&quot;,&quot;motion_fx_blur_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:31,&quot;end&quot;:39}},&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500,&quot;motion_fx_blur_level&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:7,&quot;sizes&quot;:[]},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;]}\" data-core-v316-plus=\"true\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cca8ee3 e-flex e-con-boxed e-con e-parent\" data-id=\"cca8ee3\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dc143d e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"1dc143d\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e0e0d0 elementor-widget elementor-widget-text-editor\" data-id=\"0e0e0d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Au c\u0153ur du quartier parisien du 5e arrondissement \u00e0 deux pas de l\u2019\u00e9glise Notre-Dame.\u00a0<br \/>La Fourmi Ail\u00e9e est un restaurant litt\u00e9raire, cosy et chaleureux.<br \/>La Fourmi Ail\u00e9e allie un design contemporain \u00e0 une atmosph\u00e8re chaleureuse et conviviale, cr\u00e9ant ainsi un lieu unique o\u00f9 la g\u00e9n\u00e9rosit\u00e9 et la gastronomie se rejoignent harmonieusement.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7e16be6 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"7e16be6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"http:\/\/eteenpentedouce.com\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">L'\u00e9t\u00e9 en pente douce<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-879195e e-flex e-con-boxed e-con e-child\" data-id=\"879195e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fab2ebd e-flex e-con-boxed e-con e-parent\" data-id=\"fab2ebd\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8822521 e-con-full e-flex e-con e-child\" data-id=\"8822521\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b84206d elementor-widget elementor-widget-menu-anchor\" data-id=\"b84206d\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\nbody.elementor-page .elementor-widget-menu-anchor{margin-bottom:0}<\/style>\t\t<div id=\"histoire\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3bb34c5 elementor-widget elementor-widget-heading\" data-id=\"3bb34c5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\">Fait avec amour<a style=\"text-decoration:none; color: black;\"a href=\"https:\/\/lafourmiailee.com\/index.php\/2023\/07\/27\/segredos-das-slots-do-aviator-estrategias-para-os-casinos-portugueses\/\"\/\/>.<\/a><br>Simplement exquis<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a9ab8dc elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"a9ab8dc\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"has-text-align-center has-text-color has-link-color wp-elements-9be5c98aeeece8997dd55732be81bdbe\">Notre carte est \u00e9labor\u00e9e en suivant attentivement la saisonnalit\u00e9 des ingr\u00e9dients. De cette mani\u00e8re, nous souhaitons recr\u00e9er chez vous cette atmosph\u00e8re chaleureuse et conviviale que l\u2019on trouve dans les repas familiaux, en n\u2019oubliant pas nos origine m\u00e9diterran\u00e9ennes<a style=\"text-decoration:none; color: black;\"a href=\"https:\/\/lafourmiailee.com\/index.php\/2023\/05\/27\/virtualni-kazyno-v-ukrayini-perelik-krashchykh\/\"\/>.<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8aa8798 elementor-widget elementor-widget-heading\" data-id=\"8aa8798\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Salon de Th\u00e9<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f106346 elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"f106346\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p class=\"has-text-align-center has-text-color has-link-color wp-elements-b57dd5515394287ea779194c547989b4\">En plus de son restaurant, La Fourmi Ail\u00e9e vous invite \u00e0 d\u00e9couvrir son charmant salon de th\u00e9. C\u2019est l\u2019endroit id\u00e9al pour vous d\u00e9tendre, savourer une tasse de th\u00e9 parfum\u00e9 et vous d\u00e9lecter de d\u00e9licieuses p\u00e2tisseries artisanales.<\/p><p class=\"has-text-align-center has-text-color has-link-color wp-elements-96959bb22bc2ed77c77fa542083090d7\">La Fourmi Ail\u00e9e offre une ambiance cosy et chaleureuse, parfaite pour une pause gourmande \u00e0 tout moment de la journ\u00e9e.<\/p><p class=\"has-text-align-center has-text-color has-link-color wp-elements-307d0c01eb0520499141774ffe23569e\">Laissez vous tenter par une large s\u00e9lection de th\u00e9s fins provenant des meilleures plantations, soigneusement s\u00e9lectionn\u00e9s pour leur qualit\u00e9 et leurs ar\u00f4mes. Que vous pr\u00e9f\u00e9riez un th\u00e9 noir robuste, un th\u00e9 vert rafra\u00eechissant ou une infusion parfum\u00e9e, vous trouverez certainement votre bonheur parmi les choix propos\u00e9s.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-16a25aa elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"16a25aa\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/lafourmiailee.com\/index.php\/la-carte\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir le menu<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-04fed0e e-con-full e-flex e-con e-child\" data-id=\"04fed0e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b970e1 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"4b970e1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/lafourmiailee.com\/wp-content\/uploads\/2023\/12\/img_5273-1-683x1024.jpg\" class=\"attachment-large size-large wp-image-21\" alt=\"\" srcset=\"https:\/\/lafourmiailee.com\/wp-content\/uploads\/2023\/12\/img_5273-1-683x1024.jpg 683w, https:\/\/lafourmiailee.com\/wp-content\/uploads\/2023\/12\/img_5273-1-200x300.jpg 200w, https:\/\/lafourmiailee.com\/wp-content\/uploads\/2023\/12\/img_5273-1-768x1152.jpg 768w, https:\/\/lafourmiailee.com\/wp-content\/uploads\/2023\/12\/img_5273-1-1024x1536.jpg 1024w, https:\/\/lafourmiailee.com\/wp-content\/uploads\/2023\/12\/img_5273-1-1365x2048.jpg 1365w, https:\/\/lafourmiailee.com\/wp-content\/uploads\/2023\/12\/img_5273-1-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be15341 e-flex e-con-boxed e-con e-parent\" data-id=\"be15341\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-162ecaa e-flex e-con-boxed elementor-invisible e-con e-parent\" data-id=\"162ecaa\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2bf2b3e e-flex e-con-boxed e-con e-child\" data-id=\"2bf2b3e\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27ab3d5 elementor-widget elementor-widget-heading\" data-id=\"27ab3d5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La Galerie<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d949b50 elementor-shape-circle elementor-grid-0 e-grid-align-center elementor-widget elementor-widget-social-icons\" data-id=\"d949b50\" data-element_type=\"widget\" data-widget_type=\"social-icons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-social-icons.elementor-grid-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-mobile-0 .elementor-widget-container,.elementor-widget-social-icons.elementor-grid-tablet-0 .elementor-widget-container{line-height:1;font-size:0}.elementor-widget-social-icons:not(.elementor-grid-0):not(.elementor-grid-tablet-0):not(.elementor-grid-mobile-0) .elementor-grid{display:inline-grid}.elementor-widget-social-icons .elementor-grid{grid-column-gap:var(--grid-column-gap,5px);grid-row-gap:var(--grid-row-gap,5px);grid-template-columns:var(--grid-template-columns);justify-content:var(--justify-content,center);justify-items:var(--justify-content,center)}.elementor-icon.elementor-social-icon{font-size:var(--icon-size,25px);line-height:var(--icon-size,25px);width:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em));height:calc(var(--icon-size, 25px) + 2 * var(--icon-padding, .5em))}.elementor-social-icon{--e-social-icon-icon-color:#fff;display:inline-flex;background-color:#69727d;align-items:center;justify-content:center;text-align:center;cursor:pointer}.elementor-social-icon i{color:var(--e-social-icon-icon-color)}.elementor-social-icon svg{fill:var(--e-social-icon-icon-color)}.elementor-social-icon:last-child{margin:0}.elementor-social-icon:hover{opacity:.9;color:#fff}.elementor-social-icon-android{background-color:#a4c639}.elementor-social-icon-apple{background-color:#999}.elementor-social-icon-behance{background-color:#1769ff}.elementor-social-icon-bitbucket{background-color:#205081}.elementor-social-icon-codepen{background-color:#000}.elementor-social-icon-delicious{background-color:#39f}.elementor-social-icon-deviantart{background-color:#05cc47}.elementor-social-icon-digg{background-color:#005be2}.elementor-social-icon-dribbble{background-color:#ea4c89}.elementor-social-icon-elementor{background-color:#d30c5c}.elementor-social-icon-envelope{background-color:#ea4335}.elementor-social-icon-facebook,.elementor-social-icon-facebook-f{background-color:#3b5998}.elementor-social-icon-flickr{background-color:#0063dc}.elementor-social-icon-foursquare{background-color:#2d5be3}.elementor-social-icon-free-code-camp,.elementor-social-icon-freecodecamp{background-color:#006400}.elementor-social-icon-github{background-color:#333}.elementor-social-icon-gitlab{background-color:#e24329}.elementor-social-icon-globe{background-color:#69727d}.elementor-social-icon-google-plus,.elementor-social-icon-google-plus-g{background-color:#dd4b39}.elementor-social-icon-houzz{background-color:#7ac142}.elementor-social-icon-instagram{background-color:#262626}.elementor-social-icon-jsfiddle{background-color:#487aa2}.elementor-social-icon-link{background-color:#818a91}.elementor-social-icon-linkedin,.elementor-social-icon-linkedin-in{background-color:#0077b5}.elementor-social-icon-medium{background-color:#00ab6b}.elementor-social-icon-meetup{background-color:#ec1c40}.elementor-social-icon-mixcloud{background-color:#273a4b}.elementor-social-icon-odnoklassniki{background-color:#f4731c}.elementor-social-icon-pinterest{background-color:#bd081c}.elementor-social-icon-product-hunt{background-color:#da552f}.elementor-social-icon-reddit{background-color:#ff4500}.elementor-social-icon-rss{background-color:#f26522}.elementor-social-icon-shopping-cart{background-color:#4caf50}.elementor-social-icon-skype{background-color:#00aff0}.elementor-social-icon-slideshare{background-color:#0077b5}.elementor-social-icon-snapchat{background-color:#fffc00}.elementor-social-icon-soundcloud{background-color:#f80}.elementor-social-icon-spotify{background-color:#2ebd59}.elementor-social-icon-stack-overflow{background-color:#fe7a15}.elementor-social-icon-steam{background-color:#00adee}.elementor-social-icon-stumbleupon{background-color:#eb4924}.elementor-social-icon-telegram{background-color:#2ca5e0}.elementor-social-icon-threads{background-color:#000}.elementor-social-icon-thumb-tack{background-color:#1aa1d8}.elementor-social-icon-tripadvisor{background-color:#589442}.elementor-social-icon-tumblr{background-color:#35465c}.elementor-social-icon-twitch{background-color:#6441a5}.elementor-social-icon-twitter{background-color:#1da1f2}.elementor-social-icon-viber{background-color:#665cac}.elementor-social-icon-vimeo{background-color:#1ab7ea}.elementor-social-icon-vk{background-color:#45668e}.elementor-social-icon-weibo{background-color:#dd2430}.elementor-social-icon-weixin{background-color:#31a918}.elementor-social-icon-whatsapp{background-color:#25d366}.elementor-social-icon-wordpress{background-color:#21759b}.elementor-social-icon-x-twitter{background-color:#000}.elementor-social-icon-xing{background-color:#026466}.elementor-social-icon-yelp{background-color:#af0606}.elementor-social-icon-youtube{background-color:#cd201f}.elementor-social-icon-500px{background-color:#0099e5}.elementor-shape-rounded .elementor-icon.elementor-social-icon{border-radius:10%}.elementor-shape-circle .elementor-icon.elementor-social-icon{border-radius:50%}<\/style>\t\t<div class=\"elementor-social-icons-wrapper elementor-grid\">\n\t\t\t\t\t\t\t<span class=\"elementor-grid-item\">\n\t\t\t\t\t<a class=\"elementor-icon elementor-social-icon elementor-social-icon-instagram elementor-repeater-item-f790063\" href=\"https:\/\/www.instagram.com\/la_fourmi_ailee\/\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-screen-only\">Instagram<\/span>\n\t\t\t\t\t\t<svg class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\"><\/path><\/svg>\t\t\t\t\t<\/a>\n\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9e1a53 elementor-widget elementor-widget-inavii-grid\" data-id=\"b9e1a53\" data-element_type=\"widget\" data-widget_type=\"inavii-grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\n    <div class=\"inavii-ajax inavii-skeleton-container  inavii-grid inavii-grid__type-grid\"\n         data-items-mobile=\"9\" data-settings=\"&#x7B;&quot;feed_id&quot;&#x3A;265,&quot;posts_count&quot;&#x3A;9,&quot;posts_count_available&quot;&#x3A;9,&quot;items&quot;&#x3A;&#x5B;&#x5D;,&quot;items_desktop&quot;&#x3A;9,&quot;items_mobile&quot;&#x3A;9,&quot;is_mobile&quot;&#x3A;false,&quot;img_animation_class&quot;&#x3A;&quot;&quot;,&quot;follow_button_url&quot;&#x3A;&quot;https&#x3A;&#x5C;&#x2F;&#x5C;&#x2F;www.instagram.com&#x5C;&#x2F;la_fourmi_ailee&quot;,&quot;enable_photo_linking&quot;&#x3A;&quot;popup&quot;,&quot;target&quot;&#x3A;&quot;_self&quot;,&quot;layoutView&quot;&#x3A;&quot;overlay&quot;,&quot;imageSize&quot;&#x3A;&quot;medium&quot;,&quot;enable_avatar_lightbox&quot;&#x3A;true,&quot;avatar_url&quot;&#x3A;&quot;https&#x3A;&#x5C;&#x2F;&#x5C;&#x2F;lafourmiailee.com&#x5C;&#x2F;wp-content&#x5C;&#x2F;plugins&#x5C;&#x2F;inavii-social-feed-for-elementor&#x5C;&#x2F;assets&#x5C;&#x2F;images&#x5C;&#x2F;placehorder-user.svg&quot;,&quot;username&quot;&#x3A;&quot;la_fourmi_ailee&quot;,&quot;username_lightbox_switch&quot;&#x3A;true,&quot;widget_id&quot;&#x3A;&quot;b9e1a53&quot;,&quot;feed_type&quot;&#x3A;&quot;grid&quot;,&quot;enable_popup_follow_button&quot;&#x3A;true,&quot;enable_popup_icon_follow_button&quot;&#x3A;true,&quot;follow_popup_button_icon&quot;&#x3A;&#x7B;&quot;icon_class&quot;&#x3A;&quot;&lt;svg&#x20;aria-hidden&#x3D;&#x5C;&quot;true&#x5C;&quot;&#x20;class&#x3D;&#x5C;&quot;e-font-icon-svg&#x20;e-fab-instagram&#x5C;&quot;&#x20;viewBox&#x3D;&#x5C;&quot;0&#x20;0&#x20;448&#x20;512&#x5C;&quot;&#x20;xmlns&#x3D;&#x5C;&quot;http&#x3A;&#x5C;&#x2F;&#x5C;&#x2F;www.w3.org&#x5C;&#x2F;2000&#x5C;&#x2F;svg&#x5C;&quot;&gt;&lt;path&#x20;d&#x3D;&#x5C;&quot;M224.1&#x20;141c-63.6&#x20;0-114.9&#x20;51.3-114.9&#x20;114.9s51.3&#x20;114.9&#x20;114.9&#x20;114.9S339&#x20;319.5&#x20;339&#x20;255.9&#x20;287.7&#x20;141&#x20;224.1&#x20;141zm0&#x20;189.6c-41.1&#x20;0-74.7-33.5-74.7-74.7s33.5-74.7&#x20;74.7-74.7&#x20;74.7&#x20;33.5&#x20;74.7&#x20;74.7-33.6&#x20;74.7-74.7&#x20;74.7zm146.4-194.3c0&#x20;14.9-12&#x20;26.8-26.8&#x20;26.8-14.9&#x20;0-26.8-12-26.8-26.8s12-26.8&#x20;26.8-26.8&#x20;26.8&#x20;12&#x20;26.8&#x20;26.8zm76.1&#x20;27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9&#x20;0-35.8&#x20;1.7-67.6&#x20;9.9-93.9&#x20;36.1s-34.4&#x20;58-36.2&#x20;93.9c-2.1&#x20;37-2.1&#x20;147.9&#x20;0&#x20;184.9&#x20;1.7&#x20;35.9&#x20;9.9&#x20;67.7&#x20;36.2&#x20;93.9s58&#x20;34.4&#x20;93.9&#x20;36.2c37&#x20;2.1&#x20;147.9&#x20;2.1&#x20;184.9&#x20;0&#x20;35.9-1.7&#x20;67.7-9.9&#x20;93.9-36.2&#x20;26.2-26.2&#x20;34.4-58&#x20;36.2-93.9&#x20;2.1-37&#x20;2.1-147.8&#x20;0-184.8zM398.8&#x20;388c-7.8&#x20;19.6-22.9&#x20;34.7-42.6&#x20;42.6-29.5&#x20;11.7-99.5&#x20;9-132.1&#x20;9s-102.7&#x20;2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7&#x20;9-132.1c7.8-19.6&#x20;22.9-34.7&#x20;42.6-42.6&#x20;29.5-11.7&#x20;99.5-9&#x20;132.1-9s102.7-2.6&#x20;132.1&#x20;9c19.6&#x20;7.8&#x20;34.7&#x20;22.9&#x20;42.6&#x20;42.6&#x20;11.7&#x20;29.5&#x20;9&#x20;99.5&#x20;9&#x20;132.1s2.7&#x20;102.7-9&#x20;132.1z&#x5C;&quot;&gt;&lt;&#x5C;&#x2F;path&gt;&lt;&#x5C;&#x2F;svg&gt;&quot;&#x7D;,&quot;follow_popup_button_text&quot;&#x3A;&quot;View&#x20;on&#x20;Instagram&quot;,&quot;enable_lightbox_follow_button&quot;&#x3A;true,&quot;enable_lightbox_icon_follow_button&quot;&#x3A;true,&quot;follow_lightbox_button_icon&quot;&#x3A;&#x7B;&quot;icon_class&quot;&#x3A;&quot;&lt;svg&#x20;aria-hidden&#x3D;&#x5C;&quot;true&#x5C;&quot;&#x20;class&#x3D;&#x5C;&quot;e-font-icon-svg&#x20;e-fab-instagram&#x5C;&quot;&#x20;viewBox&#x3D;&#x5C;&quot;0&#x20;0&#x20;448&#x20;512&#x5C;&quot;&#x20;xmlns&#x3D;&#x5C;&quot;http&#x3A;&#x5C;&#x2F;&#x5C;&#x2F;www.w3.org&#x5C;&#x2F;2000&#x5C;&#x2F;svg&#x5C;&quot;&gt;&lt;path&#x20;d&#x3D;&#x5C;&quot;M224.1&#x20;141c-63.6&#x20;0-114.9&#x20;51.3-114.9&#x20;114.9s51.3&#x20;114.9&#x20;114.9&#x20;114.9S339&#x20;319.5&#x20;339&#x20;255.9&#x20;287.7&#x20;141&#x20;224.1&#x20;141zm0&#x20;189.6c-41.1&#x20;0-74.7-33.5-74.7-74.7s33.5-74.7&#x20;74.7-74.7&#x20;74.7&#x20;33.5&#x20;74.7&#x20;74.7-33.6&#x20;74.7-74.7&#x20;74.7zm146.4-194.3c0&#x20;14.9-12&#x20;26.8-26.8&#x20;26.8-14.9&#x20;0-26.8-12-26.8-26.8s12-26.8&#x20;26.8-26.8&#x20;26.8&#x20;12&#x20;26.8&#x20;26.8zm76.1&#x20;27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9&#x20;0-35.8&#x20;1.7-67.6&#x20;9.9-93.9&#x20;36.1s-34.4&#x20;58-36.2&#x20;93.9c-2.1&#x20;37-2.1&#x20;147.9&#x20;0&#x20;184.9&#x20;1.7&#x20;35.9&#x20;9.9&#x20;67.7&#x20;36.2&#x20;93.9s58&#x20;34.4&#x20;93.9&#x20;36.2c37&#x20;2.1&#x20;147.9&#x20;2.1&#x20;184.9&#x20;0&#x20;35.9-1.7&#x20;67.7-9.9&#x20;93.9-36.2&#x20;26.2-26.2&#x20;34.4-58&#x20;36.2-93.9&#x20;2.1-37&#x20;2.1-147.8&#x20;0-184.8zM398.8&#x20;388c-7.8&#x20;19.6-22.9&#x20;34.7-42.6&#x20;42.6-29.5&#x20;11.7-99.5&#x20;9-132.1&#x20;9s-102.7&#x20;2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7&#x20;9-132.1c7.8-19.6&#x20;22.9-34.7&#x20;42.6-42.6&#x20;29.5-11.7&#x20;99.5-9&#x20;132.1-9s102.7-2.6&#x20;132.1&#x20;9c19.6&#x20;7.8&#x20;34.7&#x20;22.9&#x20;42.6&#x20;42.6&#x20;11.7&#x20;29.5&#x20;9&#x20;99.5&#x20;9&#x20;132.1s2.7&#x20;102.7-9&#x20;132.1z&#x5C;&quot;&gt;&lt;&#x5C;&#x2F;path&gt;&lt;&#x5C;&#x2F;svg&gt;&quot;&#x7D;,&quot;follow_lightbox_button_text&quot;&#x3A;&quot;View&#x20;on&#x20;Instagram&quot;,&quot;is_promotion&quot;&#x3A;false,&quot;is_pro&quot;&#x3A;false&#x7D;\"\n        >\n\n                        <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n    <div class=\"inavii-image-skeleton-init\"><\/div>\n        \n        \n        \n            <\/div>\n\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e3b8319 e-flex e-con-boxed e-con e-parent\" data-id=\"e3b8319\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d940d49 elementor-widget-divider--separator-type-pattern elementor-widget-divider--no-spacing elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d940d49\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.20.0 - 20-03-2024 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#0c0d0e;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-block-end:0;flex-grow:1;border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider--element-align-start .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-start .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-start .elementor-divider__element{margin-inline-start:0}.elementor-widget-divider--element-align-end .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-end .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-end .elementor-divider__element{margin-inline-end:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-block-start:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\" style=\"--divider-pattern-url: url(&quot;data:image\/svg+xml,%3Csvg xmlns=&#039;http:\/\/www.w3.org\/2000\/svg&#039; preserveAspectRatio=&#039;xMidYMid meet&#039; overflow=&#039;visible&#039; height=&#039;100%&#039; viewBox=&#039;0 0 126 26&#039; fill=&#039;black&#039; stroke=&#039;none&#039;%3E%3Cpath d=&#039;M3,10.2c2.6,0,2.6,2,2.6,3.2S4.4,16.5,3,16.5s-3-1.4-3-3.2S0.4,10.2,3,10.2z M18.8,10.2c1.7,0,3.2,1.4,3.2,3.2s-1.4,3.2-3.2,3.2c-1.7,0-3.2-1.4-3.2-3.2S17,10.2,18.8,10.2z M34.6,10.2c1.5,0,2.6,1.4,2.6,3.2s-0.5,3.2-1.9,3.2c-1.5,0-3.4-1.4-3.4-3.2S33.1,10.2,34.6,10.2z M50.5,10.2c1.7,0,3.2,1.4,3.2,3.2s-1.4,3.2-3.2,3.2c-1.7,0-3.3-0.9-3.3-2.6S48.7,10.2,50.5,10.2z M66.2,10.2c1.5,0,3.4,1.4,3.4,3.2s-1.9,3.2-3.4,3.2c-1.5,0-2.6-0.4-2.6-2.1S64.8,10.2,66.2,10.2z M82.2,10.2c1.7,0.8,2.6,1.4,2.6,3.2s-0.1,3.2-1.6,3.2c-1.5,0-3.7-1.4-3.7-3.2S80.5,9.4,82.2,10.2zM98.6,10.2c1.5,0,2.6,0.4,2.6,2.1s-1.2,4.2-2.6,4.2c-1.5,0-3.7-0.4-3.7-2.1S97.1,10.2,98.6,10.2z M113.4,10.2c1.2,0,2.2,0.9,2.2,3.2s-0.1,3.2-1.3,3.2s-3.1-1.4-3.1-3.2S112.2,10.2,113.4,10.2z&#039;\/%3E%3C\/svg%3E&quot;);\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-837bf7f e-flex e-con-boxed e-con e-parent\" data-id=\"837bf7f\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8cde959 elementor-widget elementor-widget-menu-anchor\" data-id=\"8cde959\" data-element_type=\"widget\" data-widget_type=\"menu-anchor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div id=\"Reservation\" class=\"elementor-menu-anchor\"><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58b573b elementor-widget elementor-widget-heading\" data-id=\"58b573b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">R\u00e9server une Table<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0695f8d elementor-widget elementor-widget-text-editor\" data-id=\"0695f8d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Les r\u00e9servations pour le jour m\u00eame sont prises jusqu&#8217;\u00e0 11h via le site pour le service du midi et 18h pour le service du soir. Sinon, merci de t\u00e9l\u00e9phoner directement au 01 43 29 40 99<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43a2653 elementor-widget elementor-widget-resa_form\" data-id=\"43a2653\" data-element_type=\"widget\" data-widget_type=\"resa_form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t        <div style=\"text-align: center;\">\n            <div style=\"display: inline-block; width: 150px; margin-right: 20px; margin-top: 30px;\">\n                <label for=\"select_date\">Date<\/label>\n                <select id=\"select_date\" style=\"height: 50px; text-align: center; width: 100%;\">\n                <option value='15\/07\/2026'>15\/07\/2026<\/option><option value='16\/07\/2026'>16\/07\/2026<\/option><option value='17\/07\/2026'>17\/07\/2026<\/option><option value='18\/07\/2026'>18\/07\/2026<\/option><option value='19\/07\/2026'>19\/07\/2026<\/option><option value='20\/07\/2026'>20\/07\/2026<\/option><option value='21\/07\/2026'>21\/07\/2026<\/option><option value='22\/07\/2026'>22\/07\/2026<\/option><option value='23\/07\/2026'>23\/07\/2026<\/option><option value='24\/07\/2026'>24\/07\/2026<\/option><option value='25\/07\/2026'>25\/07\/2026<\/option><option value='26\/07\/2026'>26\/07\/2026<\/option><option value='27\/07\/2026'>27\/07\/2026<\/option><option value='28\/07\/2026'>28\/07\/2026<\/option><option value='29\/07\/2026'>29\/07\/2026<\/option><option value='30\/07\/2026'>30\/07\/2026<\/option><option value='31\/07\/2026'>31\/07\/2026<\/option><option value='01\/08\/2026'>01\/08\/2026<\/option><option value='02\/08\/2026'>02\/08\/2026<\/option><option value='03\/08\/2026'>03\/08\/2026<\/option><option value='04\/08\/2026'>04\/08\/2026<\/option><option value='05\/08\/2026'>05\/08\/2026<\/option><option value='06\/08\/2026'>06\/08\/2026<\/option><option value='07\/08\/2026'>07\/08\/2026<\/option><option value='08\/08\/2026'>08\/08\/2026<\/option><option value='09\/08\/2026'>09\/08\/2026<\/option><option value='10\/08\/2026'>10\/08\/2026<\/option><option value='11\/08\/2026'>11\/08\/2026<\/option><option value='12\/08\/2026'>12\/08\/2026<\/option><option value='13\/08\/2026'>13\/08\/2026<\/option><option value='14\/08\/2026'>14\/08\/2026<\/option><option value='15\/08\/2026'>15\/08\/2026<\/option><option value='16\/08\/2026'>16\/08\/2026<\/option><option value='17\/08\/2026'>17\/08\/2026<\/option><option value='18\/08\/2026'>18\/08\/2026<\/option><option value='19\/08\/2026'>19\/08\/2026<\/option><option value='20\/08\/2026'>20\/08\/2026<\/option><option value='21\/08\/2026'>21\/08\/2026<\/option><option value='22\/08\/2026'>22\/08\/2026<\/option><option value='23\/08\/2026'>23\/08\/2026<\/option><option value='24\/08\/2026'>24\/08\/2026<\/option><option value='25\/08\/2026'>25\/08\/2026<\/option><option value='26\/08\/2026'>26\/08\/2026<\/option><option value='27\/08\/2026'>27\/08\/2026<\/option><option value='28\/08\/2026'>28\/08\/2026<\/option><option value='29\/08\/2026'>29\/08\/2026<\/option><option value='30\/08\/2026'>30\/08\/2026<\/option><option value='31\/08\/2026'>31\/08\/2026<\/option><option value='01\/09\/2026'>01\/09\/2026<\/option><option value='02\/09\/2026'>02\/09\/2026<\/option><option value='03\/09\/2026'>03\/09\/2026<\/option><option value='04\/09\/2026'>04\/09\/2026<\/option><option value='05\/09\/2026'>05\/09\/2026<\/option><option value='06\/09\/2026'>06\/09\/2026<\/option><option value='07\/09\/2026'>07\/09\/2026<\/option><option value='08\/09\/2026'>08\/09\/2026<\/option><option value='09\/09\/2026'>09\/09\/2026<\/option><option value='10\/09\/2026'>10\/09\/2026<\/option><option value='11\/09\/2026'>11\/09\/2026<\/option><option value='12\/09\/2026'>12\/09\/2026<\/option><option value='13\/09\/2026'>13\/09\/2026<\/option><option value='14\/09\/2026'>14\/09\/2026<\/option><option value='15\/09\/2026'>15\/09\/2026<\/option><option value='16\/09\/2026'>16\/09\/2026<\/option><option value='17\/09\/2026'>17\/09\/2026<\/option><option value='18\/09\/2026'>18\/09\/2026<\/option><option value='19\/09\/2026'>19\/09\/2026<\/option><option value='20\/09\/2026'>20\/09\/2026<\/option><option value='21\/09\/2026'>21\/09\/2026<\/option><option value='22\/09\/2026'>22\/09\/2026<\/option><option value='23\/09\/2026'>23\/09\/2026<\/option><option value='24\/09\/2026'>24\/09\/2026<\/option><option value='25\/09\/2026'>25\/09\/2026<\/option><option value='26\/09\/2026'>26\/09\/2026<\/option><option value='27\/09\/2026'>27\/09\/2026<\/option><option value='28\/09\/2026'>28\/09\/2026<\/option><option value='29\/09\/2026'>29\/09\/2026<\/option><option value='30\/09\/2026'>30\/09\/2026<\/option><option value='01\/10\/2026'>01\/10\/2026<\/option><option value='02\/10\/2026'>02\/10\/2026<\/option><option value='03\/10\/2026'>03\/10\/2026<\/option><option value='04\/10\/2026'>04\/10\/2026<\/option><option value='05\/10\/2026'>05\/10\/2026<\/option><option value='06\/10\/2026'>06\/10\/2026<\/option><option value='07\/10\/2026'>07\/10\/2026<\/option><option value='08\/10\/2026'>08\/10\/2026<\/option><option value='09\/10\/2026'>09\/10\/2026<\/option><option value='10\/10\/2026'>10\/10\/2026<\/option><option value='11\/10\/2026'>11\/10\/2026<\/option><option value='12\/10\/2026'>12\/10\/2026<\/option><option value='13\/10\/2026'>13\/10\/2026<\/option><option value='14\/10\/2026'>14\/10\/2026<\/option><option value='15\/10\/2026'>15\/10\/2026<\/option><option value='16\/10\/2026'>16\/10\/2026<\/option><option value='17\/10\/2026'>17\/10\/2026<\/option><option value='18\/10\/2026'>18\/10\/2026<\/option><option value='19\/10\/2026'>19\/10\/2026<\/option><option value='20\/10\/2026'>20\/10\/2026<\/option><option value='21\/10\/2026'>21\/10\/2026<\/option><option value='22\/10\/2026'>22\/10\/2026<\/option><option value='23\/10\/2026'>23\/10\/2026<\/option><option value='24\/10\/2026'>24\/10\/2026<\/option><option value='25\/10\/2026'>25\/10\/2026<\/option><option value='26\/10\/2026'>26\/10\/2026<\/option><option value='27\/10\/2026'>27\/10\/2026<\/option><option value='28\/10\/2026'>28\/10\/2026<\/option><option value='29\/10\/2026'>29\/10\/2026<\/option><option value='30\/10\/2026'>30\/10\/2026<\/option><option value='31\/10\/2026'>31\/10\/2026<\/option><option value='01\/11\/2026'>01\/11\/2026<\/option><option value='02\/11\/2026'>02\/11\/2026<\/option><option value='03\/11\/2026'>03\/11\/2026<\/option><option value='04\/11\/2026'>04\/11\/2026<\/option><option value='05\/11\/2026'>05\/11\/2026<\/option><option value='06\/11\/2026'>06\/11\/2026<\/option><option value='07\/11\/2026'>07\/11\/2026<\/option><option value='08\/11\/2026'>08\/11\/2026<\/option><option value='09\/11\/2026'>09\/11\/2026<\/option><option value='10\/11\/2026'>10\/11\/2026<\/option><option value='11\/11\/2026'>11\/11\/2026<\/option><option value='12\/11\/2026'>12\/11\/2026<\/option><option value='13\/11\/2026'>13\/11\/2026<\/option><option value='14\/11\/2026'>14\/11\/2026<\/option><option value='15\/11\/2026'>15\/11\/2026<\/option><option value='16\/11\/2026'>16\/11\/2026<\/option><option value='17\/11\/2026'>17\/11\/2026<\/option><option value='18\/11\/2026'>18\/11\/2026<\/option><option value='19\/11\/2026'>19\/11\/2026<\/option><option value='20\/11\/2026'>20\/11\/2026<\/option><option value='21\/11\/2026'>21\/11\/2026<\/option><option value='22\/11\/2026'>22\/11\/2026<\/option><option value='23\/11\/2026'>23\/11\/2026<\/option><option value='24\/11\/2026'>24\/11\/2026<\/option><option value='25\/11\/2026'>25\/11\/2026<\/option><option value='26\/11\/2026'>26\/11\/2026<\/option><option value='27\/11\/2026'>27\/11\/2026<\/option><option value='28\/11\/2026'>28\/11\/2026<\/option><option value='29\/11\/2026'>29\/11\/2026<\/option><option value='30\/11\/2026'>30\/11\/2026<\/option><option value='01\/12\/2026'>01\/12\/2026<\/option><option value='02\/12\/2026'>02\/12\/2026<\/option><option value='03\/12\/2026'>03\/12\/2026<\/option><option value='04\/12\/2026'>04\/12\/2026<\/option><option value='05\/12\/2026'>05\/12\/2026<\/option><option value='06\/12\/2026'>06\/12\/2026<\/option><option value='07\/12\/2026'>07\/12\/2026<\/option><option value='08\/12\/2026'>08\/12\/2026<\/option><option value='09\/12\/2026'>09\/12\/2026<\/option><option value='10\/12\/2026'>10\/12\/2026<\/option><option value='11\/12\/2026'>11\/12\/2026<\/option><option value='12\/12\/2026'>12\/12\/2026<\/option><option value='13\/12\/2026'>13\/12\/2026<\/option><option value='14\/12\/2026'>14\/12\/2026<\/option><option value='15\/12\/2026'>15\/12\/2026<\/option><option value='16\/12\/2026'>16\/12\/2026<\/option><option value='17\/12\/2026'>17\/12\/2026<\/option><option value='18\/12\/2026'>18\/12\/2026<\/option><option value='19\/12\/2026'>19\/12\/2026<\/option><option value='20\/12\/2026'>20\/12\/2026<\/option><option value='21\/12\/2026'>21\/12\/2026<\/option><option value='22\/12\/2026'>22\/12\/2026<\/option><option value='23\/12\/2026'>23\/12\/2026<\/option><option value='24\/12\/2026'>24\/12\/2026<\/option><option value='25\/12\/2026'>25\/12\/2026<\/option><option value='26\/12\/2026'>26\/12\/2026<\/option><option value='27\/12\/2026'>27\/12\/2026<\/option><option value='28\/12\/2026'>28\/12\/2026<\/option><option value='29\/12\/2026'>29\/12\/2026<\/option><option value='30\/12\/2026'>30\/12\/2026<\/option><option value='31\/12\/2026'>31\/12\/2026<\/option><option value='01\/01\/2027'>01\/01\/2027<\/option><option value='02\/01\/2027'>02\/01\/2027<\/option><option value='03\/01\/2027'>03\/01\/2027<\/option><option value='04\/01\/2027'>04\/01\/2027<\/option><option value='05\/01\/2027'>05\/01\/2027<\/option><option value='06\/01\/2027'>06\/01\/2027<\/option><option value='07\/01\/2027'>07\/01\/2027<\/option><option value='08\/01\/2027'>08\/01\/2027<\/option><option value='09\/01\/2027'>09\/01\/2027<\/option><option value='10\/01\/2027'>10\/01\/2027<\/option><option value='11\/01\/2027'>11\/01\/2027<\/option><option value='12\/01\/2027'>12\/01\/2027<\/option><option value='13\/01\/2027'>13\/01\/2027<\/option><option value='14\/01\/2027'>14\/01\/2027<\/option><option value='15\/01\/2027'>15\/01\/2027<\/option><option value='16\/01\/2027'>16\/01\/2027<\/option><option value='17\/01\/2027'>17\/01\/2027<\/option><option value='18\/01\/2027'>18\/01\/2027<\/option><option value='19\/01\/2027'>19\/01\/2027<\/option><option value='20\/01\/2027'>20\/01\/2027<\/option><option value='21\/01\/2027'>21\/01\/2027<\/option><option value='22\/01\/2027'>22\/01\/2027<\/option><option value='23\/01\/2027'>23\/01\/2027<\/option><option value='24\/01\/2027'>24\/01\/2027<\/option><option value='25\/01\/2027'>25\/01\/2027<\/option><option value='26\/01\/2027'>26\/01\/2027<\/option><option value='27\/01\/2027'>27\/01\/2027<\/option><option value='28\/01\/2027'>28\/01\/2027<\/option><option value='29\/01\/2027'>29\/01\/2027<\/option><option value='30\/01\/2027'>30\/01\/2027<\/option><option value='31\/01\/2027'>31\/01\/2027<\/option><option value='01\/02\/2027'>01\/02\/2027<\/option><option value='02\/02\/2027'>02\/02\/2027<\/option><option value='03\/02\/2027'>03\/02\/2027<\/option><option value='04\/02\/2027'>04\/02\/2027<\/option><option value='05\/02\/2027'>05\/02\/2027<\/option><option value='06\/02\/2027'>06\/02\/2027<\/option><option value='07\/02\/2027'>07\/02\/2027<\/option><option value='08\/02\/2027'>08\/02\/2027<\/option><option value='09\/02\/2027'>09\/02\/2027<\/option><option value='10\/02\/2027'>10\/02\/2027<\/option><option value='11\/02\/2027'>11\/02\/2027<\/option><option value='12\/02\/2027'>12\/02\/2027<\/option><option value='13\/02\/2027'>13\/02\/2027<\/option><option value='14\/02\/2027'>14\/02\/2027<\/option><option value='15\/02\/2027'>15\/02\/2027<\/option><option value='16\/02\/2027'>16\/02\/2027<\/option><option value='17\/02\/2027'>17\/02\/2027<\/option><option value='18\/02\/2027'>18\/02\/2027<\/option><option value='19\/02\/2027'>19\/02\/2027<\/option><option value='20\/02\/2027'>20\/02\/2027<\/option><option value='21\/02\/2027'>21\/02\/2027<\/option><option value='22\/02\/2027'>22\/02\/2027<\/option><option value='23\/02\/2027'>23\/02\/2027<\/option><option value='24\/02\/2027'>24\/02\/2027<\/option><option value='25\/02\/2027'>25\/02\/2027<\/option><option value='26\/02\/2027'>26\/02\/2027<\/option><option value='27\/02\/2027'>27\/02\/2027<\/option><option value='28\/02\/2027'>28\/02\/2027<\/option><option value='01\/03\/2027'>01\/03\/2027<\/option><option value='02\/03\/2027'>02\/03\/2027<\/option><option value='03\/03\/2027'>03\/03\/2027<\/option><option value='04\/03\/2027'>04\/03\/2027<\/option><option value='05\/03\/2027'>05\/03\/2027<\/option><option value='06\/03\/2027'>06\/03\/2027<\/option><option value='07\/03\/2027'>07\/03\/2027<\/option><option value='08\/03\/2027'>08\/03\/2027<\/option><option value='09\/03\/2027'>09\/03\/2027<\/option><option value='10\/03\/2027'>10\/03\/2027<\/option><option value='11\/03\/2027'>11\/03\/2027<\/option><option value='12\/03\/2027'>12\/03\/2027<\/option><option value='13\/03\/2027'>13\/03\/2027<\/option><option value='14\/03\/2027'>14\/03\/2027<\/option><option value='15\/03\/2027'>15\/03\/2027<\/option><option value='16\/03\/2027'>16\/03\/2027<\/option><option value='17\/03\/2027'>17\/03\/2027<\/option><option value='18\/03\/2027'>18\/03\/2027<\/option><option value='19\/03\/2027'>19\/03\/2027<\/option><option value='20\/03\/2027'>20\/03\/2027<\/option><option value='21\/03\/2027'>21\/03\/2027<\/option><option value='22\/03\/2027'>22\/03\/2027<\/option><option value='23\/03\/2027'>23\/03\/2027<\/option><option value='24\/03\/2027'>24\/03\/2027<\/option><option value='25\/03\/2027'>25\/03\/2027<\/option><option value='26\/03\/2027'>26\/03\/2027<\/option><option value='27\/03\/2027'>27\/03\/2027<\/option><option value='28\/03\/2027'>28\/03\/2027<\/option><option value='29\/03\/2027'>29\/03\/2027<\/option><option value='30\/03\/2027'>30\/03\/2027<\/option><option value='31\/03\/2027'>31\/03\/2027<\/option><option value='01\/04\/2027'>01\/04\/2027<\/option><option value='02\/04\/2027'>02\/04\/2027<\/option><option value='03\/04\/2027'>03\/04\/2027<\/option><option value='04\/04\/2027'>04\/04\/2027<\/option><option value='05\/04\/2027'>05\/04\/2027<\/option><option value='06\/04\/2027'>06\/04\/2027<\/option><option value='07\/04\/2027'>07\/04\/2027<\/option><option value='08\/04\/2027'>08\/04\/2027<\/option><option value='09\/04\/2027'>09\/04\/2027<\/option><option value='10\/04\/2027'>10\/04\/2027<\/option><option value='11\/04\/2027'>11\/04\/2027<\/option><option value='12\/04\/2027'>12\/04\/2027<\/option><option value='13\/04\/2027'>13\/04\/2027<\/option><option value='14\/04\/2027'>14\/04\/2027<\/option><option value='15\/04\/2027'>15\/04\/2027<\/option><option value='16\/04\/2027'>16\/04\/2027<\/option><option value='17\/04\/2027'>17\/04\/2027<\/option><option value='18\/04\/2027'>18\/04\/2027<\/option><option value='19\/04\/2027'>19\/04\/2027<\/option><option value='20\/04\/2027'>20\/04\/2027<\/option><option value='21\/04\/2027'>21\/04\/2027<\/option><option value='22\/04\/2027'>22\/04\/2027<\/option><option value='23\/04\/2027'>23\/04\/2027<\/option><option value='24\/04\/2027'>24\/04\/2027<\/option><option value='25\/04\/2027'>25\/04\/2027<\/option><option value='26\/04\/2027'>26\/04\/2027<\/option><option value='27\/04\/2027'>27\/04\/2027<\/option><option value='28\/04\/2027'>28\/04\/2027<\/option><option value='29\/04\/2027'>29\/04\/2027<\/option><option value='30\/04\/2027'>30\/04\/2027<\/option><option value='01\/05\/2027'>01\/05\/2027<\/option><option value='02\/05\/2027'>02\/05\/2027<\/option><option value='03\/05\/2027'>03\/05\/2027<\/option><option value='04\/05\/2027'>04\/05\/2027<\/option><option value='05\/05\/2027'>05\/05\/2027<\/option><option value='06\/05\/2027'>06\/05\/2027<\/option><option value='07\/05\/2027'>07\/05\/2027<\/option><option value='08\/05\/2027'>08\/05\/2027<\/option><option value='09\/05\/2027'>09\/05\/2027<\/option><option value='10\/05\/2027'>10\/05\/2027<\/option><option value='11\/05\/2027'>11\/05\/2027<\/option><option value='12\/05\/2027'>12\/05\/2027<\/option><option value='13\/05\/2027'>13\/05\/2027<\/option><option value='14\/05\/2027'>14\/05\/2027<\/option><option value='15\/05\/2027'>15\/05\/2027<\/option><option value='16\/05\/2027'>16\/05\/2027<\/option><option value='17\/05\/2027'>17\/05\/2027<\/option><option value='18\/05\/2027'>18\/05\/2027<\/option><option value='19\/05\/2027'>19\/05\/2027<\/option><option value='20\/05\/2027'>20\/05\/2027<\/option><option value='21\/05\/2027'>21\/05\/2027<\/option><option value='22\/05\/2027'>22\/05\/2027<\/option><option value='23\/05\/2027'>23\/05\/2027<\/option><option value='24\/05\/2027'>24\/05\/2027<\/option><option value='25\/05\/2027'>25\/05\/2027<\/option><option value='26\/05\/2027'>26\/05\/2027<\/option><option value='27\/05\/2027'>27\/05\/2027<\/option><option value='28\/05\/2027'>28\/05\/2027<\/option><option value='29\/05\/2027'>29\/05\/2027<\/option><option value='30\/05\/2027'>30\/05\/2027<\/option><option value='31\/05\/2027'>31\/05\/2027<\/option><option value='01\/06\/2027'>01\/06\/2027<\/option><option value='02\/06\/2027'>02\/06\/2027<\/option><option value='03\/06\/2027'>03\/06\/2027<\/option><option value='04\/06\/2027'>04\/06\/2027<\/option><option value='05\/06\/2027'>05\/06\/2027<\/option><option value='06\/06\/2027'>06\/06\/2027<\/option><option value='07\/06\/2027'>07\/06\/2027<\/option><option value='08\/06\/2027'>08\/06\/2027<\/option><option value='09\/06\/2027'>09\/06\/2027<\/option><option value='10\/06\/2027'>10\/06\/2027<\/option><option value='11\/06\/2027'>11\/06\/2027<\/option><option value='12\/06\/2027'>12\/06\/2027<\/option><option value='13\/06\/2027'>13\/06\/2027<\/option><option value='14\/06\/2027'>14\/06\/2027<\/option><option value='15\/06\/2027'>15\/06\/2027<\/option><option value='16\/06\/2027'>16\/06\/2027<\/option><option value='17\/06\/2027'>17\/06\/2027<\/option><option value='18\/06\/2027'>18\/06\/2027<\/option><option value='19\/06\/2027'>19\/06\/2027<\/option><option value='20\/06\/2027'>20\/06\/2027<\/option><option value='21\/06\/2027'>21\/06\/2027<\/option><option value='22\/06\/2027'>22\/06\/2027<\/option><option value='23\/06\/2027'>23\/06\/2027<\/option><option value='24\/06\/2027'>24\/06\/2027<\/option><option value='25\/06\/2027'>25\/06\/2027<\/option><option value='26\/06\/2027'>26\/06\/2027<\/option><option value='27\/06\/2027'>27\/06\/2027<\/option><option value='28\/06\/2027'>28\/06\/2027<\/option><option value='29\/06\/2027'>29\/06\/2027<\/option><option value='30\/06\/2027'>30\/06\/2027<\/option><option value='01\/07\/2027'>01\/07\/2027<\/option><option value='02\/07\/2027'>02\/07\/2027<\/option><option value='03\/07\/2027'>03\/07\/2027<\/option><option value='04\/07\/2027'>04\/07\/2027<\/option><option value='05\/07\/2027'>05\/07\/2027<\/option><option value='06\/07\/2027'>06\/07\/2027<\/option><option value='07\/07\/2027'>07\/07\/2027<\/option><option value='08\/07\/2027'>08\/07\/2027<\/option><option value='09\/07\/2027'>09\/07\/2027<\/option><option value='10\/07\/2027'>10\/07\/2027<\/option><option value='11\/07\/2027'>11\/07\/2027<\/option><option value='12\/07\/2027'>12\/07\/2027<\/option><option value='13\/07\/2027'>13\/07\/2027<\/option><option value='14\/07\/2027'>14\/07\/2027<\/option><option value='15\/07\/2027'>15\/07\/2027<\/option>                <\/select>\n            <\/div>\n            <div style=\"display: inline-block; width: 150px; margin-right: 20px; margin-top: 30px;\">\n                <label for=\"select_time\">Heure<\/label>\n                <select id=\"select_time\" style=\"height: 50px; text-align: center; width: 100%;\">\n                    <option value='12:00'>12:00<\/option><option value='13:00'>13:00<\/option><option value='14:00'>14:00<\/option><option value='15:00'>15:00<\/option><option value='16:00'>16:00<\/option><option value='17:00'>17:00<\/option><option value='18:00'>18:00<\/option><option value='19:00'>19:00<\/option><option value='20:00'>20:00<\/option><option value='21:00'>21:00<\/option><option value='22:00'>22:00<\/option>                <\/select>\n            <\/div>\n            <div style=\"display: inline-block; width: 150px; margin-right: 20px; margin-top: 30px;\">\n                <label for=\"select_people\">Personnes<\/label>\n                <input type=\"number\" id=\"select_people\" value=\"2\" min=\"1\" style=\"height: 50px; text-align: center; width: 100%;\">\n            <\/div>\n            <div style=\"display: inline-block; width: 150px; margin-right: 20px; margin-top: 30px;\">\n                <label for=\"name\">Nom<\/label>\n                <input type=\"text\" id=\"name\" style=\"height: 50px; text-align: center; width: 100%;\">\n            <\/div>\n            <div style=\"display: inline-block; width: 150px; margin-right: 20px; margin-top: 30px;\">\n                <label for=\"phone\">T\u00e9l\u00e9phone<\/label>\n                <input type=\"text\" id=\"phone\" style=\"height: 50px; width: 100%;\">\n            <\/div>\n            <div style=\"display: inline-block; width: 150px; margin-right: 20px; margin-top: 30px;\">\n                <label for=\"mail\">E-mail<\/label>\n                <input type=\"email\" id=\"mail\" style=\"height: 50px; text-align: center; width: 100%;\">\n            <\/div>\n        <\/div>\n        <div style=\"text-align: center; margin-top: 60px;\">\n            <button id=\"reservation_button\" style=\"font-size: 15px; background-color: #BB956B; color: #FFFFFF; padding: 12px 30px; border-style: double; border-radius: 0; border-width: 6px; border-color: #FFFFFF; cursor: pointer;\">Reservation<\/button>\n        <\/div>\n    <script>\n        document.getElementById('reservation_button').addEventListener('click', function() {\n            var name = document.getElementById('name').value.trim();\n            var phone = document.getElementById('phone').value.trim();\n            var email_custo = document.getElementById('mail').value.trim();\n\n            if(!name || !phone || !email_custo) {\n                alert(\"Veuillez remplir tous les champs.\");\n                return;\n            }\n\n            var options = {\n                method: 'POST',\n                headers: { 'Content-Type': 'application\/x-www-form-urlencoded' },\n                body: \"nom=\" + encodeURIComponent(name) +\n                      \"&date=\" + encodeURIComponent(document.getElementById('select_date').value) +\n                      \"&hour=\" + encodeURIComponent(document.getElementById('select_time').value) +\n                      \"&phone=\" + encodeURIComponent(phone) +\n                      \"&num_people=\" + encodeURIComponent(document.getElementById('select_people').value) +\n                      \"&email_custo=\" + encodeURIComponent(email_custo)\n            };\n\n            fetch(\"wp-content\/themes\/astra\/widgets\/send_email.php\", options)\n                .then(response => response.text())\n                .then(data => {\n                    if (data.trim() === \"success\") {\n                        alert(\"La demande de r\u00e9servation a bien \u00e9t\u00e9 prise en compte.\");\n                        window.location.href = \"https:\/\/lafourmiailee.com\/index.php\/confirmation\/\";\n                    } else {\n                        alert(data);\n                    }\n                });\n        });\n    <\/script>\n        \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Au c\u0153ur du quartier parisien du 5e arrondissement \u00e0 deux pas de l\u2019\u00e9glise Notre-Dame.\u00a0La Fourmi Ail\u00e9e est un restaurant litt\u00e9raire, [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"_links":{"self":[{"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/pages\/10"}],"collection":[{"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":189,"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":447,"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/pages\/10\/revisions\/447"}],"wp:attachment":[{"href":"https:\/\/lafourmiailee.com\/index.php\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}